{"id":7392,"date":"2022-04-28T10:01:22","date_gmt":"2022-04-28T10:01:22","guid":{"rendered":"https:\/\/www.babyhealthcheck.com\/at\/?p=7392"},"modified":"2022-04-28T10:01:26","modified_gmt":"2022-04-28T10:01:26","slug":"auswirkungen-von-covid-19-auf-die-behandlung-von-seltenen-erkrankungen","status":"publish","type":"post","link":"https:\/\/www.babyhealthcheck.com\/at\/auswirkungen-von-covid-19-auf-die-behandlung-von-seltenen-erkrankungen\/","title":{"rendered":"Auswirkungen von COVID-19 auf die Behandlung von seltenen Erkrankungen"},"content":{"rendered":"\n<p><strong>Der Einfluss der COVID-19-Pandemie hat auch vor der Therapie von seltenen Erkrankungen nicht Einhalt genommen. Ein Kollateralschaden von COVID-19 ist die medizinische Routineversorgung von Erkrankten ohne COVID-19-spezifischer Betreuung.\u00a0<\/strong><\/p>\n\n\n\n<p>Im Rahmen von Therapien mit Medikamenten bei seltenen Erkrankungen, Off-Label Use und auch bei Arzneimittelstudien stellt eine Therapieunterbrechung oder die Nicht-Einhaltung der Follow-up Untersuchungen, einen Grund f\u00fcr die vorzeitige Beendigung der Behandlung dar. Die Familien sind bereits einer enormen Belastung durch die Erkrankung ausgesetzt. Der Auftrag an das medizinische Personal liegt nicht nur in der Diagnostik und Verabreichung der Medikation. Unser Behandlungsauftrag inkludiert auch, den Betroffenen weitere Unterst\u00fctzung zu geben. Durch Lockdowns gab es nicht nur Beschaffungsengp\u00e4sse, sondern auch noch andere H\u00fcrden zu meistern wie z.B. lange Anfahrtswege, mit der Angst sich mit einer zus\u00e4tzlichen t\u00f6dlichen Krankheit anzustecken, mangelnde \u00dcbernachtungsm\u00f6glichkeiten und Einkaufsm\u00f6glichkeiten. Auch der Zugang zu medizinischen Untersuchungen im niedergelassenem Bereich war erschwert.&nbsp;<\/p>\n\n\n\n<p>Die Enzymersatztherapie gilt als \u201eessentielle Leistung\u201c und wird auch in der Pandemie fortgesetzt. Die Familien sind motiviert, trotz zus\u00e4tzlicher Belastung, die Therapie fortzusetzen. Faktoren wie verz\u00f6gerte Diagnose durch Terminverschiebung beim Aufkl\u00e4rungsgespr\u00e4ch, gestrichene Untersuchungen, die vor der Medikation essentiell sind, personelle Engp\u00e4sse durch Quarant\u00e4ne als COVID-19 Erkrankter, als Kontaktperson oder zur Betreuung von Angeh\u00f6rigen durch geschlossene Kinderg\u00e4rten und Schulen, fehlende zus\u00e4tzliche Therapien wie Logo-, Physiotherapie und \u00e4hnliches, auch geschlossene Spezialschulen, andere \u201enicht essentielle\u201c Medikation war Mangelware und auch, dass Kinder ohne ihre Familie bzw. Betreuungsperson Behandlungen durchmachten mussten, Eltern durften ihre Kinder w\u00e4hrend des Krankenhausaufenthalts nicht oder sehr eingeschr\u00e4nkt besuchen, Telefon- bzw. Videovisiten statt dem Pr\u00e4senz-Gespr\u00e4ch, erschweren weiters. Die negativen Auswirkungen auf menschliche Isolation ist ein wesentlicher Faktor f\u00fcr Gesunde wie Kranke. Wir sind im Zeitalter der individualisierten und personalisierten Medizin angekommen. Die Pandemie hat viele dieser so wichtigen Ans\u00e4tze in der Begleitung von Familien mit chronischen Erkrankungen unterbunden. Auch in einer Pandemie gibt es noch andere medizinische Bed\u00fcrfnisse die man zuk\u00fcnftig nicht vergessen darf.\u00a0<\/p>\n\n\n\n<p><strong>Referenz<\/strong>:<\/p>\n\n\n\n<ul><li><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/?sort=date&amp;term=Mortensen+A&amp;cauthor_id=35045884\">Mortensen<\/a>&nbsp;A,&nbsp;<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/?sort=date&amp;term=Raebel+EM&amp;cauthor_id=35045884\">Raebel<\/a>&nbsp;EM,&nbsp;<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/?sort=date&amp;term=Wiseman+S&amp;cauthor_id=35045884\">Wiseman<\/a>&nbsp;S. Impact of the COVID-19 pandemic on access to the cerliponase alfa managed access agreement in England for CLN2 treatment.&nbsp;Orphanet J Rare Dis.&nbsp;2022 Jan 19;17(1):19.<\/li><li><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/?sort=date&amp;term=Elstein+D&amp;cauthor_id=34367919\">Elstein<\/a>&nbsp;<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/34367919\/#affiliation-1\">D<\/a>,&nbsp;<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/?sort=date&amp;term=Giugliani+R&amp;cauthor_id=34367919\">Giugliani<\/a>&nbsp;<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/34367919\/#affiliation-2\">R<\/a>,&nbsp;<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/?sort=date&amp;term=Muenzer+J&amp;cauthor_id=34367919\">Muenzer<\/a>&nbsp;<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/34367919\/#affiliation-3\">J<\/a>,&nbsp;<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/?sort=date&amp;term=Schenk+J&amp;cauthor_id=34367919\">Schenk<\/a>&nbsp;<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/34367919\/#affiliation-4\">J<\/a>,&nbsp;<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/?sort=date&amp;term=Schwartz+IVD&amp;cauthor_id=34367919\">Schwartz<\/a>&nbsp;<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/34367919\/#affiliation-2\">I<\/a>,&nbsp;<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/?sort=date&amp;term=Anagnostopoulou+C&amp;cauthor_id=34367919\">Anagnostopoulou<\/a>&nbsp;C. Impact of the COVID-19 pandemic on the standard of care for patients with lysosomal storage diseases: A survey of healthcare professionals in the Fabry, Gaucher, and Hunter Outcome Survey registries. Mol Genet Metab Rep.&nbsp;2021 Sep;28:100788.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Der Einfluss der COVID-19-Pandemie hat auch vor der Therapie von seltenen Erkrankungen nicht Einhalt genommen. Ein Kollateralschaden von COVID-19 ist die medizinische Routineversorgung von Erkrankten ohne COVID-19-spezifischer Betreuung.\u00a0 Im Rahmen von Therapien mit Medikamenten bei seltenen Erkrankungen, Off-Label Use und auch bei Arzneimittelstudien stellt eine Therapieunterbrechung oder die Nicht-Einhaltung der Follow-up Untersuchungen, einen Grund f\u00fcr<\/p>\n","protected":false},"author":1,"featured_media":6847,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.babyhealthcheck.com\/at\/wp-content\/uploads\/sites\/6\/2022\/01\/supportforphysicians.jpg",1600,766,false],"thumbnail":["https:\/\/www.babyhealthcheck.com\/at\/wp-content\/uploads\/sites\/6\/2022\/01\/supportforphysicians.jpg",150,72,false],"medium":["https:\/\/www.babyhealthcheck.com\/at\/wp-content\/uploads\/sites\/6\/2022\/01\/supportforphysicians.jpg",300,144,false],"medium_large":["https:\/\/www.babyhealthcheck.com\/at\/wp-content\/uploads\/sites\/6\/2022\/01\/supportforphysicians.jpg",768,368,false],"large":["https:\/\/www.babyhealthcheck.com\/at\/wp-content\/uploads\/sites\/6\/2022\/01\/supportforphysicians.jpg",1024,490,false],"1536x1536":["https:\/\/www.babyhealthcheck.com\/at\/wp-content\/uploads\/sites\/6\/2022\/01\/supportforphysicians.jpg",1536,735,false],"2048x2048":["https:\/\/www.babyhealthcheck.com\/at\/wp-content\/uploads\/sites\/6\/2022\/01\/supportforphysicians.jpg",1600,766,false]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/www.babyhealthcheck.com\/at\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Der Einfluss der COVID-19-Pandemie hat auch vor der Therapie von seltenen Erkrankungen nicht Einhalt genommen. Ein Kollateralschaden von COVID-19 ist die medizinische Routineversorgung von Erkrankten ohne COVID-19-spezifischer Betreuung.\u00a0 Im Rahmen von Therapien mit Medikamenten bei seltenen Erkrankungen, Off-Label Use und auch bei Arzneimittelstudien stellt eine Therapieunterbrechung oder die Nicht-Einhaltung der Follow-up Untersuchungen, einen Grund f\u00fcr","_links":{"self":[{"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/posts\/7392"}],"collection":[{"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/comments?post=7392"}],"version-history":[{"count":1,"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/posts\/7392\/revisions"}],"predecessor-version":[{"id":7393,"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/posts\/7392\/revisions\/7393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/media\/6847"}],"wp:attachment":[{"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/media?parent=7392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/categories?post=7392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/tags?post=7392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}