{"id":7342,"date":"2022-02-09T19:28:34","date_gmt":"2022-02-09T19:28:34","guid":{"rendered":"https:\/\/www-staging.babyhealthcheck.com\/at\/?page_id=7342"},"modified":"2023-12-15T16:39:41","modified_gmt":"2023-12-15T16:39:41","slug":"allgemeine-geschaeftsbedingungen","status":"publish","type":"page","link":"https:\/\/www.babyhealthcheck.com\/at\/allgemeine-geschaeftsbedingungen\/","title":{"rendered":"Allgemeine Gesch\u00e4ftsbedingungen"},"content":{"rendered":"\n<p><strong>ALLGEMEINE GESCH\u00c4FTSBEDINGUNGEN der ARCHIMEDlife GmbH<br>Stand: M\u00e4rz 2018<\/strong><\/p>\n\n\n\n<p>1. Geltungsbereich<br>1.1 Diese Allgemeinen Gesch\u00e4ftsbedingungen gelten f\u00fcr s\u00e4mtliche Vertr\u00e4ge, Angebote, Verk\u00e4ufe, Lieferungen und Dienstleistungen der ARCHIMEDlife GmbH.<br>1.2 Soweit die Parteien einen schriftlichen Vertrag schlie\u00dfen, gehen die Regelungen des Vertrages diesen AGB vor, sofern Widerspr\u00fcche zu den vorliegenden AGBs bestehen. In diesem Fall gelten diese AGB nur f\u00fcr jene Punkte, die nicht vom Vertrag geregelt werden.<br>1.3 ARCHIMEDlife GmbH besch\u00e4ftigt sich mit der Durchf\u00fchrung bzw. Bereitstellung von biochemischen und genetischen Analysedienstleistungen, weiters auch mit der Entwicklung von neuen labordiagnostischen Tests und Bereitstellungen von Forschungs- und sonstigen Dienstleistungen im Life Science Bereich.<\/p>\n\n\n\n<p>2. Begriffsdefinitionen Querverweise<br>2.1 \u201eAGB\u201c: Diese Allgemeinen Gesch\u00e4ftsbedingungen der ARCHIMEDlife GmbH<br>2.2 \u201eARCHIMEDlife\u201c: ARCHIMEDlife GmbH.<br>2.3 \u201eVertragspartner\u201c: Der, allenfalls erst potentielle Vertragspartner von ARCHIMEDlife, und\/oder jede Person, die Anspr\u00fcche aus einer Vorvertrags oder Vertragsbeziehung mit oder gegen ARCHIMEDlife ableitet.<\/p>\n\n\n\n<p><strong>ALLGEMEINE BESTIMMUNGEN<\/strong><\/p>\n\n\n\n<p>3. Schriftform \u2013 \u00c4nderung der AGB<br>3.1 Entgegenstehende Allgemeine Gesch\u00e4ftsbedingungen oder von diesen AGB abweichende Bedingungen sind nur dann wirksam, wenn sie von ARCHIMEDlife ausdr\u00fccklich und schriftlich anerkannt werden. Dies gilt insbesondere f\u00fcr die Bestell und Einkaufsbedingungen des Vertragspartners, wenn diese mit diesen Bedingungen in Widerspruch stehen oder bestimmte Bedingungen ausschlie\u00dfen. Produktlieferbedingungen gelten entsprechend f\u00fcr Dienstleistungen. Auch Vertragserf\u00fcllungshandlungen oder die Annahme von Zahlungen durch ARCHIMEDlife gelten nicht als Zustimmung zu von diesen AGB abweichenden Vertragsbedingungen.<br>3.2 Von diesen AGB abweichende oder diese erg\u00e4nzende Vereinbarungen gelten nur f\u00fcr das jeweilige Rechtsgesch\u00e4ft, nicht jedoch f\u00fcr andere Rechtsgesch\u00e4fte, insbesondere nicht f\u00fcr Folgegesch\u00e4fte.<br>3.3 \u00c4nderungen dieser AGB gelten als genehmigt und sind auch f\u00fcr bestehende Vertr\u00e4ge wirksam, wenn der Vertragspartner nicht innerhalb eines Monats nach Zugang der ge\u00e4nderten AGB Widerspruch dagegen erhebt. Die \u00dcbermittlung der ge\u00e4nderten AGB kann auch auf elektronischem Weg (z.B. per E-Mail) erfolgen.<\/p>\n\n\n\n<p>4. Angebot und Annahme<br>4.1 Sofern von ARCHIMEDlife nicht anders angegeben, sind ihre Angebote \u2013 entweder schriftliche Anbote oder solche, die per E-Mail versendet werden oder sich aus den auf der Homepage angef\u00fchrten Leistungen ergeben unverbindlich.<br>4.2 Kostenvoranschl\u00e4ge von ARCHIMEDlife sind unverbindlich und entgeltlich Abschlagszahlung bei Nicht-Beauftragung.<br>4.3 Angebote von Vertragspartnern gelten erst dann als angenommen, wenn sie von ARCHIMEDlife schriftlich best\u00e4tigt oder tats\u00e4chlich ausgef\u00fchrt worden sind. Blo\u00dfe Zugangsbest\u00e4tigungen stellen noch keine verbindliche Annahme des Angebots durch ARCHIMEDlife dar.<br>4.4 Angebote von Vertragspartnern k\u00f6nnen von ARCHIMEDlife innerhalb von vier Wochen ab Zugang angenommen werden.<\/p>\n\n\n\n<p>5. Preise<br>5.1 Die Preise von ARCHIMEDlife verstehen sich in EURO (\u20ac) und als Nettopreise exklusive Umsatzsteuer (Mehrwertsteuer). Die Umsatzsteuer (Mehrwertsteuer) wird zus\u00e4tzlich in der jeweils gesetzlichen H\u00f6he in Rechnung gestellt, sofern eine solche anf\u00e4llt.<br>5.2 Preisangaben sind im Zweifel nicht als Pauschalpreis zu verstehen. Die Preise basieren auf den aktuellen Material und<br>Lohnkosten. Sollten sich diese Kosten \u00e4ndern, kann ein Aufpreis auf die Preise erhoben werden.<\/p>\n\n\n\n<p>6. F\u00e4lligkeit \u2013 Zahlungsbedingungen<br>6.1 Ist ARCHIMEDlife zur Vorleistung verpflichtet ist ARCHIMEDlife berechtigt nach alleinigem Ermessen eine Vorauszahlung zu verlangen; wenn nach Vertragsabschluss Umst\u00e4nde zu Tage treten, wonach sich die Liquidit\u00e4ts- und\/oder Verm\u00f6genssituation des Vertragspartnern wesentlich verschlechtert hat (dies wird insb. vermutet, wenn der Vertragspartner Zahlungen gegen\u00fcber ARCHIMEDlife nicht fristgerecht leistet), ist ARCHIMEDlife jedenfalls berechtigt, vor Beginn der Leistungserbringung oder, sofern diese bereits begonnen hat, vor Fortsetzung der Leistungserbringung, eine angemessene Vorauszahlung oder sonstige geeignete Sicherheit (z.B. Bankgarantie) zu verlangen. Sollte der Vertragspartner die Anzahlung oder Sicherheit nicht fristgerecht leisten oder beibringen, ist ARCHIMEDlife unter Setzung einer 14t\u00e4gigen Nachfrist zum R\u00fccktritt vom Vertrag oder seinen noch ausst\u00e4ndigen Teilleistungen berechtigt. Der Vertragspartner kann aus einem solchen R\u00fccktritt keine Anspr\u00fcche gegen ARCHIMEDlife, gleich welcher Art, ableiten.<br>Dar\u00fcber hinaus beh\u00e4lt sich die ARCHIMEDlife das Recht vor, den Vertrag ohne weitere Benachrichtigung zu k\u00fcndigen, wenn ein Insolvenzverfahren gegen den Vertragspartner eingeleitet wird. Dar\u00fcber hinaus werden alle ausst\u00e4ndigen Kosten sofort f\u00e4llig, wenn ein Konkursverfahren gegen den Partner eingeleitet wird oder der Vertragspartner die vereinbarte Zahlung einstellt. ARCHIMEDlife kann den Vertrag auch aus den oben genannten Gr\u00fcnden bei unvollst\u00e4ndiger Lieferung durch den Vertragspartner k\u00fcndigen. Im Falle einer K\u00fcndigung durch ARCHIMEDlife werden unbeschadet etwaiger Schadensersatzanspr\u00fcche der ARCHIMEDlife bereits erbrachte Leistungen (oder ein Teil davon) vertragsgem\u00e4\u00df abgerechnet und bezahlt. ARCHIMEDlife beh\u00e4lt sich jedoch vor, bereits gelieferte Produkte \/ Dienstleistungen zur\u00fcckzufordern.<br>6.2 An und Abschlagszahlungen werden nicht verzinst.<br>6.3 Alle Zahlungen sind spesenfrei und ohne Abzug (z.B. Skonto) binnen 30 Tagen ab Rechnungsdatum zur Zahlung ohne Abzug f\u00e4llig.<br>6.4 Bei \u00dcberschreitung der Zahlungsfrist, wenn auch nur hinsichtlich einer einzelnen Teilzahlung, verfallen gew\u00e4hrte Verg\u00fcnstigungen (Rabatte, Abschl\u00e4ge, etc.) und werden der Rechnung zugerechnet bzw. nachverrechnet.<br>6.5 Eine Aufrechnungsbefugnis steht dem Vertragspartner nur insoweit zu, als Gegenanspr\u00fcche gerichtlich festgestellt oder von ARCHIMEDlife schriftlich anerkannt worden sind.<br>6.6 Bei Zahlungsverzug gelten die gesetzlichen Verzugszinsen. Ab der zweiten Mahnung werden ohne weitere Vorank\u00fcndigung automatisch \u20ac 40, Mahngeb\u00fchren verrechnet. Weiters hat der Vertragspartner s\u00e4mtliche \u00fcber den vorgenannten Pauschalbetrag hinausgehenden Kosten, d.h. die f\u00fcr die Betreibung eines Anspruchs anfallenden Mahn und Inkassokosten sowie Rechtsanwaltskosten, zu ersetzen.<br>6.7 ARCHIMEDlife beh\u00e4lt sich das Recht vor, etwaige Forderungen gegen offene Rechnungen aufzurechnen. Eingehende Zahlungen werden zuerst den Zinsen und dann dem Auftraggeber gutgeschrieben; \u00e4ltere R\u00fcckst\u00e4nde sollen vor den j\u00fcngeren bezahlt werden. Kommt der Vertragspartner in Verzug mit der Zahlung oder einer sonstigen vertraglichen Verpflichtung, kann ARCHIMEDlife entweder auf Erf\u00fcllung des Vertrages bestehen und a) die Erf\u00fcllung eigener Verpflichtungen aufschieben, bis solche Zahlungen oder Verpflichtungen erf\u00fcllt sind b) den gesamten ausstehenden Betrag (sofort zahlbar) zur\u00fcckzufordern und c) f\u00e4llige Verzugszinsen berechnen oder den Vertrag unbeschadet etwaiger Schadensersatzanspr\u00fcche nach angemessener Frist k\u00fcndigen v<br>6.8 Unbeschadet ihrer sonstigen Rechte ist ARCHIMEDlife im Fall des Zahlungsverzugs berechtigt, jegliche noch ausstehenden Leistungen oder Teilleistungen, gleich welcher Art, aufgrund des Vertrages oder anderer gleichartiger Vertr\u00e4ge aus der Gesch\u00e4ftsverbindung mit dem Vertragspartnern bis zur vollst\u00e4ndigen Zahlung des Entgelts einzustellen.<\/p>\n\n\n\n<p>7. Rechte des Vertragspartners bei Verzug<br>7.1 Bei Verzug mit der Vertragserf\u00fcllung durch ARCHIMEDlife von mehr als vier Wochen steht dem Vertragspartner ein Recht auf R\u00fccktritt vom Vertrag nach Setzung einer angemessenen Nachfrist zu. Die Setzung der Nachfrist hat schriftlich unter gleichzeitiger Androhung des R\u00fccktritts zu erfolgen.<\/p>\n\n\n\n<p>8. Leistungsausf\u00fchrung<br>8.1 Dem Vertragspartner zumutbare sachlich gerechtfertigte geringf\u00fcgige \u00c4nderungen der Leistungsausf\u00fchrung durch ARCHIMEDlife gelten als vorweg genehmigt.<br>8.2 Sachlich gerechtfertigte Teillieferungen und -leistungen sind zul\u00e4ssig und k\u00f6nnen in Rechnung gestellt werden.<br>8.3 Materialien, die ARCHIMEDlife vom Vertragspartner zur Verf\u00fcgung gestellt werden, sind an die ARCHIMEDlife GmbH, Leberstrasse 20\/2, 1110 Wien, \u00d6sterreich, Europa, kostenfrei zu liefern. Versand oder Lieferkosten gehen zu Lasten des Vertragspartners. Der Vertragspartner haftet f\u00fcr alle zur Verf\u00fcgung gestellten Materialien und h\u00e4lt ARCHIMEDlife diesbez\u00fcglich schad- und klagslos.<br>8.4 Liefertermine gelten, sofern nicht ausdr\u00fccklich schriftlich anders vereinbart, als voraussichtliche Liefertermine, die sich jedoch in begr\u00fcndete F\u00e4llen verschieben k\u00f6nnen. Die Einhaltung der (best\u00e4tigten) Liefertermine durch ARCHIMEDlife setzt voraus, dass der Vertragspartner rechtzeitig geeignete Unterlagen oder Material, insbesondere Muster oder Proben, zur Verf\u00fcgung stellt. ARCHIMEDlife beh\u00e4lt sich vor, Teillieferungen vorzunehmen und zu berechnen. Bei Vorliegen von unvorhersehbaren Umst\u00e4nden (wie z.B. bewaffneter Konflikt, beh\u00f6rdliche Vorgaben, F\u00e4lle h\u00f6herer Gewalt wie Feuer, Erdbeben, sonstige Naturkatastrophen, etc; Versp\u00e4tung bei Transport und Zollabfertigung, Verkehrsbehinderung, Maschinenbruch, Material und Energieverlust, Schwierigkeiten und versp\u00e4tete Zustellung durch Lieferanten, Nichtlieferung, versp\u00e4tete Lieferung oder mangelhafte Qualit\u00e4t der von ARCHIMEDlife f\u00fcr die Ausf\u00fchrung der Bestellung ben\u00f6tigten Materialien) ist ARCHIMEDlife berechtigt, den Liefertermin entsprechend dem Umfang und der Dauer dieser Umst\u00e4nde und deren Folgen zu verl\u00e4ngern, ohne dadurch einen K\u00fcndigungsgrund zu setzen.<br>8.5 H\u00e4lt ARCHIMEDlife die vereinbarten Lieferbedingungen \u2013 mit Ausnahme der in Punkt 8.4 angef\u00fchrten Umst\u00e4nde \u2013 nicht ein, so kann der Vertragspartner den Vertrag nur unter Einhaltung einer angemessenen Nachfrist von mindestens zwei Wochen zur Beseitigung des Leistungsverzuges aufl\u00f6sen, und zwar nur dann, wenn ARCHIMEDlife Vorsatz oder grobe Fahrl\u00e4ssigkeit zur Last gelegt werden kann.<\/p>\n\n\n\n<p>9. Geistiges Eigentum<br>9.1 Anbote, Projektentw\u00fcrfe, Materialen zu Diagnostikinitiativen, Pl\u00e4ne, Skizzen, Kostenvoranschl\u00e4ge und sonstige Unterlagen oder Markenrechte, technische oder sonstige Studien oder neu entwickelte Diagnostikmethoden etc., die von ARCHIMEDlife beigestellt oder durch Beitrag von ARCHIMEDlife entstanden sind, bleiben geistiges Eigentum von ARCHIMEDlife. Die Verwendung solcher Unterlagen au\u00dferhalb der bestimmungsgem\u00e4\u00dfen Nutzung, insbesondere die Weitergabe, Bearbeitung, Ver\u00e4nderung, Vervielf\u00e4ltigung, Ver\u00f6ffentlichung und Zurverf\u00fcgungstellung sowie Verbreitung mittels elektronischer Medien einschlie\u00dflich auch nur auszugsweisen Kopierens bedarf der ausdr\u00fccklichen Zustimmung von ARCHIMEDlife.<br>9.2 Der Vertragspartner und ARCHIMEDlife verpflichten sich wechselseitig zur Geheimhaltung des ihnen aus der Gesch\u00e4ftsbeziehung zugegangenen Wissens Dritten gegen\u00fcber.<br>9.3 Soweit der Vertragspartner Informationen und Unterlagen an ARCHIMEDlife \u00fcbergibt, hat er ARCHIMEDlife hinsichtlich aller Anspr\u00fcchen schad- und klaglos halten, die von Dritten aufgrund der Verletzung gewerblicher Schutzrechte oder Urheberrechte gegen\u00fcber ARCHIMEDlife geltend gemacht werden.<br>9.4 Werden w\u00e4hrend eines Projektes neue geistige Eigentumsrechte geschaffen, ist ARCHIMEDlife ausschlie\u00dflich Eigent\u00fcmer und kann diese f\u00fcr sich beanspruchen und eintragen, sofern nicht schriftlich etwas anderes vereinbart wurde. Der Vertragspartner hat das Recht, die f\u00fcr ihn erstellten Ergebnisse nur innerhalb seines Unternehmens und unter diesem Vertrag zu verwenden.<\/p>\n\n\n\n<p>10. Gew\u00e4hrleistung<br>10.1 Die Gew\u00e4hrleistungsfrist f\u00fcr die von ARCHIMEDlife erbrachten Leistungen betr\u00e4gt 6 Monate ab der Leistungserbringung.<br>10.2 Rechte des Vertragspartners wegen M\u00e4ngeln an den gelieferten Waren, erbrachten Dienstleistungen oder errichteten Werken setzen voraus, dass der Vertragspartner die gelieferte Ware oder das Werk innerhalb einer angemessenen Frist auf M\u00e4ngel untersucht und diese ARCHIMEDlife innerhalb einer Frist von 7 Tagen ab Leistungserbringung (s. Pkt. 10.1.) schriftlich angezeigt werden (M\u00e4ngelr\u00fcge). Versteckte M\u00e4ngel sind unverz\u00fcglich, l\u00e4ngstens aber binnen 7 Tagen nach ihrer Entdeckung zu r\u00fcgen. Wird die M\u00e4ngelr\u00fcge nicht rechtzeitig erhoben, gilt die gelieferte Ware bzw. das Werk als genehmigt. Anspr\u00fcche aus Gew\u00e4hrleistung, Schadenersatz wegen des Mangels selbst und Irrtum sind in diesem Fall ausgeschlossen.<br>10.3 Unter Ausschluss der gesetzlichen Bestimmung des \u00a7 924 ABGB muss der Vertragspartner beweisen, dass von ihm behauptete M\u00e4ngel bereits im Zeitpunkt der \u00dcbergabe vorhanden waren.<br>10.4 ARCHIMEDlife sind zur M\u00e4ngelbehebung zumindest zwei Versuche einzur\u00e4umen.<br>10.5 Ein Wandlungsbegehren kann ARCHIMEDlife durch Verbesserung oder angemessene Preisminderung abwenden, sofern es sich um keinen wesentlichen und unbehebbaren Mangel handelt.<br>10.6 Behebungen eines vom Vertragspartner behaupteten Mangels stellen kein Anerkenntnis dieses vom Vertragspartner behauptenden Mangels dar.<br>10.7 Sind die M\u00e4ngelbehauptungen des Vertragspartners unberechtigt, ist der Vertragspartner verpflichtet, ARCHIMEDlife entstandene Aufwendungen f\u00fcr die Feststellung der M\u00e4ngelfreiheit oder Fehlerbehebung zu ersetzen. Das Entgelt von ARCHIMEDlife bemisst sich in diesem Fall nach den tats\u00e4chlichen Aufwendungen.<br>10.8 Eine etwaige Nutzung oder Verarbeitung des mangelhaften Leistungsgegenstandes, durch welche ein weitergehender Schaden droht oder eine Ursachenerhebung erschwert oder verhindert wird, ist vom Vertragspartnern unverz\u00fcglich einzustellen, soweit dies zumutbar ist.<br>10.9 Die mangelhafte Lieferung oder Proben sind \u2013 sofern wirtschaftlich vertretbar \u2013 an ARCHIMEDlife zu retournieren.<br>10.10 Verbrauchsmaterialien, die f\u00fcr die Durchf\u00fchrung der Analysen verwendet wurden, sind von der Gew\u00e4hrleistung ausgeschlossen. Dies gilt ebenso f\u00fcr den Fall eines mangelhaften Ergebnisses, wenn die ARCHIMEDlife \u00fcbermittelten Proben nicht m\u00e4ngelfrei gewesen sind.<br>10.11 Es werden jene Produkteigenschaften geschuldet, die im Hinblick auf die Zulassungsvorschriften, Bedienungsanleitungen und sonstige produktbezogene Anleitungen und Hinweise (insb. auch Kontrolle und Wartung) von ARCHIMEDlife, dritten Herstellern oder Importeuren vom Vertragspartner unter Ber\u00fccksichtigung dessen Kenntnisse und Erfahrungen erwartet werden k\u00f6nnen. Der Vertragspartner hat ARCHIMEDlife hinsichtlich Regressanspr\u00fcchen schad- und klaglos zu halten.<br>10.12 W\u00e4hrend der Gew\u00e4hrleistungsfrist ersetzte Leistungen gehen in das Eigentum von ARCHIMEDlife \u00fcber. M\u00e4ngel, die auf Nachl\u00e4ssigkeit oder Missbrauch der Leistung durch den Vertragspartner oder Dritte zur\u00fcckzuf\u00fchren sind, sind von der Gew\u00e4hrleistung ausgeschlossen. \u00dcbliche Abweichungen in Umfang und \/ oder Qualit\u00e4t der gelieferten Dienstleistung stellen keinen Mangel oder keine Nichteinhaltung des Vertrages dar. Die Gew\u00e4hrleistung entf\u00e4llt, wenn ohne schriftliche Zustimmung von ARCHIMEDlife ein Versuch zur Nachbesserung der von dem Vertragspartner oder einem nicht autorisierten Dritten erbrachten Leistungen unternommen wird. Rechnungen f\u00fcr solche Reparaturen werden von ARCHIMEDlife nicht akzeptiert, auch die Gew\u00e4hrleistungsfrist wird dadurch nicht verl\u00e4ngert.<\/p>\n\n\n\n<p>11. Schadensersatzanspr\u00fcche \u2013 Umfang der Haftung<br>11.1 Schadensersatzanspr\u00fcche gegen ARCHIMEDlife sind ausgeschlossen, es sei denn, der Schaden beruht auf grober Fahrl\u00e4ssigkeit oder Vorsatz von ARCHIMEDlife. Die Haftung von ARCHIMEDlife beschr\u00e4nkt sich in jedem Fall auf unmittelbare Sch\u00e4den an der Lieferung. Die ARCHIMEDlife haftet nicht f\u00fcr Sch\u00e4den an nicht vertragsgegenst\u00e4ndlichen Waren, f\u00fcr entgangenen Gewinn sowie f\u00fcr direkte oder indirekte Folgesch\u00e4den. Weitergehende Anspr\u00fcche des Vertragspartners gegen die ARCHIMEDlife sind ausgeschlossen.<br>11.2 Gegen\u00fcber Vertragspartnern ist die Haftung beschr\u00e4nkt mit dem Haftungsh\u00f6chstbetrag einer allenfalls von ARCHIMEDlife abgeschlossenen Haftpflichtversicherung. Diese Beschr\u00e4nkung gilt auch hinsichtlich des Schadens an einer Sache, die ARCHIMEDlife zur Bearbeitung \u00fcbernommen hat.<br>11.3 Beschr\u00e4nkungen und Ausschl\u00fcsse der Haftung umfassen auch Anspr\u00fcche gegen Mitarbeiter, Vertreter und Erf\u00fcllungsgehilfen von ARCHIMEDlife aufgrund Sch\u00e4digungen, die diese dem Vertragspartner ohne Bezug auf einen Vertrag ihrerseits mit dem Vertragspartner zuf\u00fcgen.<br>11.4 Schadenersatzanspr\u00fcche sind vom Vertragspartner bei sonstigem Verfall binnen 6 Monaten gerichtlich geltend zu machen.<br>11.5 Wenn und soweit der Vertragspartner f\u00fcr Sch\u00e4den, f\u00fcr die ARCHIMEDlife haftet, Versicherungsleistungen durch eine eigene oder zu seinen Gunsten abgeschlossene Schadenversicherung (z.B. Haftpflicht, Kasko, Transport, Feuer, Betriebsunterbrechungsversicherung, usw.) in Anspruch nehmen kann, verpflichtet sich der Vertragspartner zur Inanspruchnahme der Versicherungsleistung und beschr\u00e4nkt sich die Haftung von ARCHIMEDlife gegen\u00fcber dem Vertragspartnern insoweit auf die Nachteile, die dem Vertragspartnern durch die Inanspruchnahme dieser Versicherung entstehen (z.B. h\u00f6here Versicherungspr\u00e4mie).<\/p>\n\n\n\n<p>12. Sonstiges<br>12.1 Ausschlie\u00dflicher Gerichtsstand f\u00fcr alle Streitigkeiten im Zusammenhang mit dem Vertrag und seiner Durchf\u00fchrung ist das sachlich zust\u00e4ndige Gericht in Wien. ARCHIMEDlife ist jedoch berechtigt, den Vertragspartner auch an dem Gericht zu klagen, das f\u00fcr dessen Sitz zust\u00e4ndig ist.<br>12.2 Erf\u00fcllungsort ist Wien.<br>12.3 F\u00fcr die Rechtsbeziehungen der Parteien gilt ausschlie\u00dflich \u00f6sterreichisches Recht unter Ausschluss des UN-Kaufrechts sowie nationaler und internationaler Kollisionsnormen.<br>12.4 Sollten Bestimmungen dieser AGB ganz oder teilweise nichtig oder unwirksam sein oder werden, bleiben die \u00fcbrigen Bestimmungen davon unber\u00fchrt. Unwirksame oder undurchf\u00fchrbare Bestimmungen sind dem Sinn und Zweck dieser Bedingungen entsprechend durch rechtswirksame und durchf\u00fchrbare Bestimmungen zu ersetzen, welche in ihrer wirtschaftlichen Auswirkung den unwirksamen oder undurchf\u00fchrbaren Bestimmungen so nahe kommen, wie rechtlich m\u00f6glich. Dies gilt auch f\u00fcr den Fall etwaiger Vertragsl\u00fccken.<br>12.5 Der Vertragspartner erteilt seine Zustimmung, dass ARCHIMEDlife \u00fcbermittelte Daten automationsunterst\u00fctzt gespeichert und verarbeitet werden k\u00f6nnen und erkl\u00e4rt sich ausdr\u00fccklich damit einverstanden, dass s\u00e4mtliche den Vertragspartnern betreffenden Daten, insbesondere Stammdaten samt Angaben zu Bestellungen, die im Rahmen der Gesch\u00e4ftsbeziehungen mit den Vertragspartnern bekannt geworden sind, an Mutter und Tochtergesellschaften von ARCHIMEDlife im Rahmen der Berichts, Controlling und Revisionswesen weitergegeben werden. Der Vertragspartner hat ein Widerrufsrecht laut Datenschutzgesetz.<br>12.6 Der Vertragspartner ist verpflichtet, ARCHIMEDlife \u00c4nderungen seiner Gesch\u00e4ftsadresse bekannt zu geben, solange das vertragsgegenst\u00e4ndliche Rechtsgesch\u00e4ft nicht beiderseitig vollst\u00e4ndig erf\u00fcllt ist. Wird eine solche Mitteilung unterlassen, so gelten Erkl\u00e4rungen auch dann als zugegangen, wenn sie an die zuletzt bekannt gegebene Adresse des Vertragspartners gesendet werden.<br>12.7 ARCHIMEDlife ist berechtigt, nach eigener Wahl Subunternehmer mit der Leistungserbringung zu beauftragen.<\/p>\n\n\n\n<p>13. Eigentumsvorbehalt<br>13.1 Die von ARCHIMEDlife an den Vertragspartner erbrachten Leistungen bleiben bis zur vollst\u00e4ndigen Bezahlung des Kaufpreises, einschlie\u00dflich Zinsen und Kosten der Einziehung, Eigentum von ARCHIMEDlife. Dieses Recht bleibt vorbehalten, solange ARCHIMEDlife aus anderen Lieferungen Anspr\u00fcche gegen den Vertragspartner hat. Techniken und Methoden, die von ARCHIMEDlife entwickelt wurden, d\u00fcrfen nicht an Dritte weitergegeben werden, es sei denn, es wurde etwas anderes schriftlich vereinbart. Der Vertragspartner darf das Knowhow im Zusammenhang mit den von ARCHIMEDlife erbrachten Leistungen zu keinem kommerziellen Zweck nutzen, es sei denn, es wurde etwas anderes schriftlich vereinbart. Im Falle der Nichteinhaltung beh\u00e4lt sich ARCHIMEDlife das Recht vor, eine Strafe (die nicht nach richterlichem Ermessen reduziert werden kann) in H\u00f6he von EUR 20.000 pro Versto\u00df in Rechnung zu stellen.<\/p>\n\n\n\n<p>14. Annahmeverzug<br>14.1 Im Fall des Annahmeverzugs des Vertragspartners ist ARCHIMEDlife berechtigt, nach Setzung einer angemessenen Nachfrist vom Vertrag oder noch ausst\u00e4ndigen Teilleistungen zur\u00fcckzutreten. Als Annahmeverzug gilt insbesondere auch die Verletzung von den Vertragspartner treffenden Mitwirkungspflichten. Weitere aus dem Annahmeverzug des Vertragspartners resultierende Anspr\u00fcche von ARCHIMEDlife bleiben unber\u00fchrt.<\/p>\n\n\n\n<p>15. \u00dcbernahme \u2013 Gefahren\u00fcbergang\/Gew\u00e4hrleistung<br>15.1 Der Versand der Ware\/Dienstleistung\/Bericht bzw. Befund erfolgt stets auf Gefahr des Vertragspartners, unabh\u00e4ngig vom vereinbarten Preis und auch dann, wenn ARCHIMEDlife die Sendung durchf\u00fchrt oder organisiert. Der Gefahren\u00fcbergang auf den Vertragspartner erfolgt daher mit dem Zeitpunkt der \u00dcbergabe in den Versand. Wird die Versendung aus den R\u00e4umlichkeiten der ARCHIMEDlife in der Leberstrasse 20\/2, 1110 Wien, \u00d6sterreich, Europa aus Gr\u00fcnden verz\u00f6gert, die ARCHIMEDlife nicht zu vertreten hat, geht die Gefahr von ARCHIMEDlife auf den Vertragspartner \u00fcber, sofern dieser dar\u00fcber benachrichtigt worden ist, dass das Produkt lieferbereit ist. Mit der solcherart erfolgten \u00dcbernahme geht die Gefahr auf den Vertragspartnern \u00fcber und Gew\u00e4hrleistungsfristen beginnen zu laufen.<br>15.2 Die Gefahr f\u00fcr von ARCHIMEDlife angelieferte und am Leistungsort gelagerte Materialien tr\u00e4gt der Vertragspartner.<\/p>\n\n\n\n<p><strong>BESONDERE BESTIMMUNGEN F\u00dcR DIE DURCHF\u00dcHRUNG UND BEREITSTELLUNG VON PROBEN<\/strong><\/p>\n\n\n\n<p>16. Bestellung von Proben<br>16.1 Der Vertragspartner kann bei ARCHIMEDlife entweder mittels schriftlicher oder elektronischer Bestellung oder durch Einsendung der von ARCHIMEDlife zur Verf\u00fcgung gestellten Trockenblutkarten biochemische oder genetische Testdienstleistungen f\u00fcr spezifische Proben von spezifischen Patienten bestellen. Diese Bestellungen m\u00fcssen von einem verantwortlichen Arzt des Patienten an ARCHIMEDlife \u00fcbermittelt werden und eine Bestellung bzw. Anmeldung \u00fcber das von ARCHIMEDlife zur Verf\u00fcgung gestellte Webportal vornehmen.<br>16.2 Der Auftrag\/die Bestellung muss eine Kopie der unterfertigten Einverst\u00e4ndniserkl\u00e4rung des Patienten bzw. dessen gesetzlicher Vertreter enthalten; diese wird von ARCHIMEDlife entweder postalisch, per E-Mail oder mittels Webportal zur Verf\u00fcgung gestellt.<br>16.3 ARCHIMEDlife beh\u00e4lt sich das Recht vor, die Bearbeitung eines Auftrags oder einer Probe zu verweigern, wenn unvollst\u00e4ndige Unterlagen \u00fcbermittelt werden bzw. die Einverst\u00e4ndniserkl\u00e4rung des Patienten fehlt.<\/p>\n\n\n\n<p>17. Versand von Proben<br>17.1 Der Versand der Proben hat an ARCHIMEDlife GmbH, Leberstra\u00dfe 20\/2, 1110 Wien, \u00d6sterreich zu erfolgen.<\/p>\n\n\n\n<p>18. Probenanalyse und Bericht\/Befunderstattung<br>18.1 Wenn die erforderlichen Unterlagen vorliegen und ARCHIMEDlife die Abarbeitung des Auftrages best\u00e4tigt hat, werden die \u00fcbermittelten patientenspezifischen Proben, die auf den Trockenblutkarten oder anderem Medium vorhanden sind, analysiert und dar\u00fcber ein entsprechender Bericht bzw. Befund verfasst.<br>18.2 Jede ARCHIMEDlife \u00fcbermittelte Probe sowie die von ARCHIMEDlife durchgef\u00fchrten beauftragten biochemischen und\/oder genetischen Tests erfolgen auf dem h\u00f6chsten und aktuellsten wissenschaftlichen und analytischen Standard. Dennoch kann nicht ausgeschlossen werden, dass in seltenen F\u00e4llen genetische oder biochemische Tests nicht das richtige Ergebnis anzeigen, wenn beispielsweise die ARCHIMEDlife \u00fcbermittelte Qualit\u00e4t des Materials nicht ausreichend ist oder aus unvorhersehbaren oder unbekannten Gr\u00fcnden fehlschl\u00e4gt, die nicht im Voraus beeinflusst werden kann. In derartigen F\u00e4llen ist ARCHIMEDlife nicht verantwortlich und \/ oder haftbar f\u00fcr das unvollst\u00e4ndige, m\u00f6glicherweise irref\u00fchrende oder sogar falsche Ergebnis der vorgenommenen Analyse, wenn dieser Umstand f\u00fcr ARCHIMEDlife nicht erkennbar war.<br>18.3 ARCHIMEDlife \u00fcbermittelt die nach abgeschlossener Analyse verfassten Berichte bzw. Befunde entweder dem verantwortlichen Arzt postalisch an die von ihm angegebene \u00e4rztliche Adresse bzw. Spitalsadresse oder \u00fcber das von ARCHIMEDlife zur Verf\u00fcgung gestellte WEBPORTAL.<br>18.4 Jeder von ARCHIMEDlife verfasste und \u00fcbermittelte Bericht bzw. Befund gilt nur f\u00fcr die dort angef\u00fchrte bestimmte Probe, die unter den angegebenen Testbedingungen und -anforderungen getestet wurde. F\u00fcr die \u00dcbermittlung und Mitteilung des Ergebnisses an den betreffenden Patienten ist ausschlie\u00dflich der verantwortliche Arzt zust\u00e4ndig \u2013ARCHIMEDlife haftet in diesem Zusammenhang nicht f\u00fcr Abz\u00fcge, Schlussfolgerungen oder Verallgemeinerungen, die vom verantwortlichen Arzt, dem Partner oder Dritten aus einem Bericht bzw. Befund gezogen werden.<br>18.5 Sollte ARCHIMEDlife die urspr\u00fcngliche Analyse bzw. den Bericht bzw. Befund nachpr\u00fcfen m\u00fcssen und dabei weiterf\u00fchrende zus\u00e4tzliche Aufwendungen und Arbeiten erforderlich werden, so ist ARCHIMEDlife berechtigt, diese Mehrkosten zu verrechnen, sofern sich das urspr\u00fcngliche Ergebnis der Analyse best\u00e4tigt.<br>18.6 Die dem Verantwortlichen zur Verf\u00fcgung gestellten Berichte bzw. Befunde k\u00f6nnen von ihm (je nach Umfang der Einwilligungserkl\u00e4rung des Patienten) bzw. dem betreffenden Patienten an den zust\u00e4ndigen Hausarzt oder Dritten \u00fcbermittelt werden, wobei der von ARCHIMEDlife verfasste Bericht bzw. Befund dabei in seiner Form unver\u00e4ndert bleiben muss. Sollten sich Unklarheiten, Unzul\u00e4nglichkeiten oder anderen m\u00f6gliche M\u00e4ngel in dem Bericht bzw. Befund f\u00fcr den verantwortlichen Arzt ergeben, so muss ARCHIMEDlife dar\u00fcber unverz\u00fcglich schriftlich, elektronisch oder telefonisch unter der dem verantwortlichen Arzt bekannt gegebenen Hotline benachrichtigt werden und weitere Erl\u00e4uterungen und eventuelle \u00c4nderungen des Berichtes bzw. Befunds bzw. eine erneute Analyse verlangt werden. ARCHIMEDlife wird unverz\u00fcglich eine erneute Untersuchung der Probe vornehmen.<\/p>\n\n\n\n<p>19. Nutzung der an ARCHIMEDlife \u00fcbermittelten Daten<br>19.1 Mit Auftragserteilung und Auftragsannahme durch ARCHIMEDlife stimmt der Vertragspartner zu, dass ARCHIMEDlife die \u00fcbermittelten Daten speichern und f\u00fcr eigene kommerzielle und nicht kommerzielle Zwecke sowie insbesondere f\u00fcr wissenschaftliche Zwecke nutzen darf. Patientendaten, die ARCHIMEDlife \u00fcbermittelt werden, werden von ARCHIMEDlife ausnahmslos anonymisiert genutzt werden. ARCHIMEDlife wird sicherstellen, dass die erhaltenen Daten anonymisiert werden und niemand R\u00fcckschl\u00fcsse auf den Patienten ziehen kann.<\/p>\n\n\n\n<p><strong>ALLGEMEINE GESCH\u00c4FTSBEDINGUNGEN F\u00dcR DIE NUTZUNG DER HOMEPAGE UND DEN DATENBANKZUGRIFF AUF DAS ARCHIMEDLIFE WEBPORTAL der ARCHIMEDlife GmbH<\/strong><br><strong>Stand: M\u00e4rz 2018<\/strong><\/p>\n\n\n\n<p>1. Geltungsbereich<br>1.1 Diese Allgemeinen Gesch\u00e4ftsbedingungen gelten f\u00fcr alle Nutzer der Homepage, der Datenbank sowie des WEBPORTALs der ARCHIMEDlife GmbH (ARCHIMEDlife in Folge genannt).<br>1.2 Soweit die Parteien einen schriftlichen Vertrag schlie\u00dfen, gehen die Regelungen des Vertrages diesen AGB vor, sofern Widerspr\u00fcche zu den vorliegenden AGBs bestehen. In diesem Fall gelten diese AGB nur f\u00fcr jene Punkte, die nicht vom Vertrag geregelt werden.<br>1.3 ARCHIMEDlife besch\u00e4ftigt sich mit der Durchf\u00fchrung bzw. Bereitstellung von biochemischen und genetischen Analysen, sowie von Studien (Forschungsdienstleistungen f\u00fcr Analytik). Durch die von ARCHIMEDlife betriebene Homepage samt WEBPORTAL wird dem Benutzer erm\u00f6glicht, auf die Analysenergebnisse der vom Benutzer an ARCHIMEDlife \u00fcbermittelten Proben zuzugreifen (Befund\u00fcbermittlung).<\/p>\n\n\n\n<p>2. Begriffsdefinitionen Querverweise<br>2.1 \u201eAGB\u201c: Diese Allgemeinen Gesch\u00e4ftsbedingungen der ARCHIMEDlife GmbH<br>2.2 \u201eARCHIMEDlife\u201c: ARCHIMEDlife GmbH.<br>2.3 \u201eBenutzer\u201c: S\u00e4mtliche Personen, die die Homepage, den Datenzugriff und das WEBPORTAL von ARCHIMED nutzen.<\/p>\n\n\n\n<p><strong>A. ALLGEMEINE BESTIMMUNGEN<\/strong><\/p>\n\n\n\n<p>3. Nutzungsrechte<br>3.1 Alle Inhalte der Website (einschlie\u00dflich Text, Designs, Grafiken, Logos, Icons, Bilder, Audiodateien, Downloads, Schnittstellen, Codes und Software und dergleichen) sowie alle anderen Unterlagen und Materialien, die von ARCHIMEDlife auf der Homepage zur Verf\u00fcgung gestellt werden, sind durch Urheber und\/oder Markenrecht gesch\u00fctzt. Die Nutzung und Verwendung dieser Inhalte ist nur nach Ma\u00dfgabe der AGBs zul\u00e4ssig.<br>3.2 Unter der Voraussetzung, dass die Inhalte der Website nicht ver\u00e4ndert werden, d\u00fcrfen die auf der Website enthaltenen Informationen \u00fcber die Dienstleistungen, das Angebot sowie fachlichen Input heruntergeladen, ausgedruckt oder abgespeichert werden. Unzul\u00e4ssig ist es, dabei Inhalt zu ver\u00e4ndern oder zu l\u00f6schen sowie Copyright, Marken oder andere Eigentumshinweise aus den Unterlagen, die angesehen, heruntergeladen oder ausgedruckt werden, zu entfernen. Bei Verdacht des missbr\u00e4uchlichen Verwendens beh\u00e4lt sich ARCHIMEDlife das Recht vor, das Nutzungsrecht des einzelnen Benutzers teilweise oder zu G\u00e4nze zu beschr\u00e4nken oder aufzuheben. Jede andere Nutzung der Website bzw. deren Inhalte \u2013 einschlie\u00dflich der Reproduktion, Verteilung, Kommunikation oder<br>\u00f6ffentliche Zug\u00e4nglichmachung \u2013 ist ohne die Zustimmung von ARCHIMEDlife ausdr\u00fccklich untersagt.<\/p>\n\n\n\n<p>3.3 Der Benutzer ist nur nach vorheriger schriftlicher Zustimmung von ARCHIMEDlife berechtigt, den Firmennamen, das Warenzeichen, das Loge oder sonstige Marken oder Kennzeichen von ARCHIMEDlife zu verwenden. Dies umfasst auch die Aufnahme in Referenzlisten oder Pressemitteilungen und dgl.<\/p>\n\n\n\n<p>4. \u00dcberwachung der Nutzung<br>4.1 ARCHIMEDlife \u00fcberpr\u00fcft, ob bei den Zugriffen und der Nutzung der Website sowie des WEBPORTALs die AGBs eingehalten werden. Dies kann u.U. auch die Auswertung von Serverprotokollen umfassen.<br>4.2 ARCHIMEDlife weist darauf hin, dass es den Webanalysedienst Google Analytics, einen Webanalysedienst von Google, sowie Matomo (vormals Piwik) verwendet. Mit den dabei verwendeten Cookies erh\u00e4lt ARCHIMEDlife Informationen \u00fcber Ihre Nutzung des WEBPORTALs, um dadurch den Service des WEBPORTALs noch weiter zu verbessern. Wir weisen darauf hin, dass im Rahmen der Nutzung von Google Analytics diese durch die Cookies erlangten Informationen an Google auf Servern in den USA \u00fcbertragen und dort gespeichert werden. Ihre IP-Adresse wird innerhalb von Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum gek\u00fcrzt. Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt. Google wird diese Informationen im Auftrag von ARCHIMEDlife verwenden, um Ihre Nutzung des WEBPORTALs zu bewerten, um Reports \u00fcber die Websiteaktivit\u00e4ten f\u00fcr die Websitebetreiber zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen zu erbringen. Die im Rahmen von Google Analytics von Ihrem Browser \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt. Sie k\u00f6nnen die Verwendung von Cookies ablehnen, indem Sie die entsprechenden Einstellungen in Ihrem Browser ausw\u00e4hlen. Auch dabei gilt jedoch, dass Sie in diesem Fall nicht mehr alle Funktionen des WEBPORTALs werden nutzen k\u00f6nnen. Sie k\u00f6nnen die Deaktivierung der Verfolgung durch Google Analytics mit Wirkung f\u00fcr die Zukunft auch ablehnen, indem Sie das Google Analytics-Deaktivierungs-Browser-Addon f\u00fcr Ihren aktuellen Webbrowser herunterladen und installieren: http:\/\/tools.google.com\/dlpage\/gaoptout?hl=de.<\/p>\n\n\n\n<p>5. Verf\u00fcgbarkeit der Homepage und des ARCHIMEDlife WEBPORTALs, Wartung\/Updates<br>5.1 Der Benutzer nimmt zur Kenntnis, dass ARCHIMEDlife sowohl die Homepage als auch das WEBPORTAL laufend aktualisiert und verbessert. Dazu sind zeitweise Wartung und\/oder Aktualisierungen erforderlich, w\u00e4hrend derer u.U. die Datenbank offline gesetzt werden muss. ARCHIMEDlife kann keine fixe Verf\u00fcgbarkeitsrate der Homepage und des WEBPORTALs zusichern.<br>5.2 Sollte es durch notwendige Updates oder Wartungen erforderlich werden, dass die Homepage oder das WEBPORTAL f\u00fcr mehr als 12 Stunden offline gesetzt werden m\u00fcssen, dann wird sich ARCHIMEDlife bem\u00fchen, die Benutzer davor im Voraus zu informieren.<\/p>\n\n\n\n<p>6. Haftungsbeschr\u00e4nkung f\u00fcr die Homepage<br>6.1 ARCHIMEDlife \u00fcbernimmt keine Verantwortung f\u00fcr die Verf\u00fcgbarkeit des Internetauftrittes, die Richtigkeit, Vollst\u00e4ndigkeit oder Aktualit\u00e4t der auf der Website bereitgestellten Inhalte, Daten oder Informationen. Es besteht seitens ARCHIMEDlife keine Verpflichtung, die Informationen auf der Website regelm\u00e4\u00dfig zu \u00fcberpr\u00fcfen oder zu aktualisieren. Jede Haftung f\u00fcr unmittelbare, mittelbare oder sonstige Sch\u00e4den, unabh\u00e4ngig von deren Ursachen, die aus der Benutzung oder Nichtverf\u00fcgbarkeit der Daten und Informationen dieser Homepage oder sonst durch die Nutzung des Portals entstehen k\u00f6nnten, wird ausgeschlossen. F\u00fcr die technische Anbindung des Benutzers an das WEBPORTAL von ARCHIMEDlife hat der Benutzer selbst zu sorgen.<br>6.2 Auf der Homepage von ARCHIMEDlife enthaltene Links auf externe Homepages liegen au\u00dferhalb der Kontrolle von ARCHIMEDlife. ARCHIMEDlife \u00fcbernimmt daher f\u00fcr diese fremden Inhalte keine Verantwortung. Die auf der Homepage enthaltenen Links dienen als Dienstleistung, um dem Benutzer weiterf\u00fchrende Informationen zu erm\u00f6glichen. F\u00fcr den Inhalt der verlinkten Seiten sind ausschlie\u00dflich deren Betreiber verantwortlich. ARCHIMEDlife haftet nicht f\u00fcr Sch\u00e4den, die aus der Nutzung der verlinkten Homepages entstehen.<\/p>\n\n\n\n<p>7. Sonstiges<br>7.1 Ausschlie\u00dflicher Gerichtsstand f\u00fcr alle Streitigkeiten im Zusammenhang mit dem Vertrag und seiner Durchf\u00fchrung ist das sachlich zust\u00e4ndige Gericht in Wien. ARCHIMEDlife ist jedoch berechtigt, den Vertragspartner auch an dem Gericht zu klagen, das f\u00fcr dessen Sitz zust\u00e4ndig ist.<br>7.2 Erf\u00fcllungsort ist Wien.<br>7.3 F\u00fcr die Rechtsbeziehungen der Parteien gilt ausschlie\u00dflich \u00f6sterreichisches Recht unter Ausschluss des UN-Kaufrechts sowie nationaler und internationaler Kollisionsnormen.<br>7.4 Sollten Bestimmungen dieser AGB ganz oder teilweise nichtig oder unwirksam sein oder werden, bleiben die \u00fcbrigen Bestimmungen hiervon unber\u00fchrt. Unwirksame oder undurchf\u00fchrbare Bestimmungen sind dem Sinn und Zweck dieser Bedingungen entsprechend durch rechtswirksame und durchf\u00fchrbare Bestimmungen zu ersetzen, welche in ihrer wirtschaftlichen Auswirkung den unwirksamen oder undurchf\u00fchrbaren Bestimmungen so nahe kommen, wie rechtlich m\u00f6glich. Dies gilt auch f\u00fcr den Fall etwaiger Vertragsl\u00fccken.<br>7.5 Der Benutzer erteilt seine Zustimmung, dass ARCHIMEDlife \u00fcbermittelte Daten automationsunterst\u00fctzt gespeichert und verarbeitet werden k\u00f6nnen und sich ausdr\u00fccklich damit einverstanden, dass s\u00e4mtliche den Benutzer betreffenden Daten, insbesondere Stammdaten samt Angaben zu Bestellungen, die im Rahmen der Gesch\u00e4ftsbeziehungen mit den Vertragspartnern bekannt geworden sind, an Mutter und Tochtergesellschaften von ARCHIMEDlife im Rahmen der Berichts, Controlling und Revisionswesen weitergegeben werden. Der Benutzer hat Widerrufsrecht laut Datenschutzgesetz.<\/p>\n\n\n\n<p><strong>B. BESONDERE BESTIMMUNGEN F\u00dcR DIE NUTZUNG DES WEBPORTALS<\/strong><\/p>\n\n\n\n<p>1. Allgemeines<br>1.1 Der Vertragspartner kann bei ARCHIMEDlife entweder mittels schriftlicher oder elektronischer Bestellung oder durch Einsendung der von ARCHIMEDlife zur Verf\u00fcgung gestellten Trockenblutkarten oder \u00e4hnlichem bereitgestellten Medium biochemische und\/ oder genetische Analysedienstleistungen f\u00fcr spezifische Proben von spezifischen Patienten bestellen. Diese Bestellungen m\u00fcssen von einem verantwortlichen Arzt des Patienten an ARCHIMEDlife \u00fcbermittelt werden und eine Bestellung bzw. Anmeldung \u00fcber das von ARCHIMEDlife zur Verf\u00fcgung gestellte WEBPORTAL vornehmen (WEBPORTAL ist ausschlie\u00dflich \u00c4rzten vorbehalten).<br>1.2 Der Auftrag \/ die Bestellung muss entweder eine Kopie der unterfertigten Einverst\u00e4ndniserkl\u00e4rung des Patienten bzw. dessen gesetzlicher Vertreter enthalten oder im WEBPORTAL das Vorhandensein der unterfertigten Einverst\u00e4ndniserkl\u00e4rung durch Anklicken des daf\u00fcr vorgesehenen Buttons best\u00e4tigt werden; diese wird von ARCHIMEDlife entweder postalisch, per E-Mail oder mittels WEBPORTAL zur Verf\u00fcgung gestellt. ARCHIMEDlife haftet nicht f\u00fcr die Richtigkeit der dort get\u00e4tigten Angaben, sondern darf sich auf die Best\u00e4tigung des Vorliegens der unterfertigten Einverst\u00e4ndniserkl\u00e4rung des Patienten durch den einsendenden Arzt verlassen.<br>1.3 ARCHIMEDlife bietet unter der Internetadresse WEBPORTAL.archimedlife.com die M\u00f6glichkeit an, auf das WEBPORTAL zuzugreifen. Im Rahmen des WEBPORTALs wird es den dazu berechtigten Benutzern (ausschlie\u00dflich \u00c4rzten) erm\u00f6glicht, die Berichte \u00fcber die erfolgten Analysen der von ihnen an ARCHIMEDlife \u00fcbermittelten Proben online abzurufen oder einen Auftrag an ARCHIMEDlife zur \u00dcberpr\u00fcfung und Befundung zu \u00fcbermitteln. Die im WEBPORTAL abrufbaren Analysen bzw. Berichte bzw. Befunde sind nur f\u00fcr den verantwortlichen Arzt einsehbar und umfassen die gegen\u00fcber ARCHIMEDlife \u00fcbermittelten Daten der Testperson. Andere, als der verantwortliche Arzt, d\u00fcrfen keinen Zugriff auf den Account des Arztes im WEBPORTAL erhalten.<\/p>\n\n\n\n<p>2. Zugang zum WEBPORTAL<br>2.1 Der Zugang zum WEBPORTAL wird nur \u00c4rzten gestattet, die von ARCHIMEDlife zu analysierende Proben \u00fcbermitteln bzw. \u00fcbermittelt haben.<br>2.2 Voraussetzung f\u00fcr die Erstanmeldung im WEBPORTAL ist die Best\u00e4tigung der fachlichen Befugnis bzw. der ausreichenden fachlichen Qualifikationen und Referenzen. Der Benutzer hat wahrheitsgem\u00e4\u00dfe Angaben \u00fcber seine fachliche Qualifikation zu machen und seine \u00e4rztliche Berufsbefugnis nach den auf ihn anwendbaren nationalen \u00e4rzterechtlichen Bestimmungen zu best\u00e4tigen. ARCHIMEDlife beh\u00e4lt sich vor, (allenfalls beglaubigte) Nachweise \u00fcber die \u00e4rztliche Berufsbefugnis vom Benutzer anzufordern, wenn Zweifel an den Angaben bestehen. Kommt der Benutzer dieser Anforderung nicht nach, so kann ARCHIMEDlife entweder die Registrierung im WEBPORTAL verweigern oder ein bereits angelegtes Benutzerkonto entweder bis zum Nachweis der Berufsbefugnis oder dauerhaft sperren bzw. l\u00f6schen.<br>2.3 Der Benutzer muss im Rahmen seiner Erstanmeldung seine pers\u00f6nlichen Daten samt m\u00f6glichen Kontaktdaten, insbesondere E-Mail Adresse sowie die im WEBPORTAL verpflichtend geforderten Angaben anf\u00fchren, bevor er Zugriffsrechte auf das WEBPORTAL erh\u00e4lt. ARCHIMEDlife \u00fcbermittelte dem Benutzer auf die von ihm bekannt gegeben E-Mail Adresse einen Link, der zu weiterf\u00fchrenden Registrierung erforderlich ist. Weiters hat der Benutzer die Allgemeinen Gesch\u00e4ftsbedingungen sowie die Datenschutzerkl\u00e4rung zu akzeptieren, andernfalls wird kein Benutzerkonto seitens ARCHIMED angelegt und eine Nutzung des WEBPORTALS ist nicht m\u00f6glich.<br>2.4 ARCHIMEDlife erstellt nach Erhalt der erforderlichen Daten ein dem Benutzer zugeordnetes Benutzerkonto, f\u00fcr das der Benutzer ein Passwort ben\u00f6tigt. Der Benutzer ist ausschlie\u00dflich pers\u00f6nlich berechtigt, Zugriff auf dieses Benutzerkonto zu nehmen \u2013 die Weitergabe dieser Zugangsdaten an Dritte (auch an Mitarbeiter des Benutzers) ist untersagt. Sollte der Benutzer Kenntnis davon erlangen, dass eine nicht berechtigte Person seine Zugangsdaten erhalten hat, so hat er ARCHIMEDlife dar\u00fcber unverz\u00fcglich zu informieren. ARCHIMEDlife wird nach Einlangen der Mitteilung die Sperre dieses Benutzerkontos verf\u00fcgen, um sicherzustellen, dass keine Analyseberichte von einer dazu nicht berechtigte Person eingesehen werden k\u00f6nnen. Sollte eine unberechtigte Person \u00fcber den Zugriffsaccount des Arztes Zugang zum WEBPORTAL erlangen, so haftet ARCHIMEDlife nicht f\u00fcr daraus entstehende Sch\u00e4den.<br>2.5 Sollte der Benutzer mehr als zw\u00f6lf Wochen lang nicht auf sein Benutzerkonto zugreifen, so ist ARCHIMED aus Sicherheitsgr\u00fcnden berechtigt, das Benutzerkonto vor\u00fcbergehen zu sperren. Der Benutzer hat sich bei Wiederaufnahme des Zugangs zu dem Benutzerkonto an ARCHIMED zu wenden, um eine Freischaltung zu erhalten.<\/p>\n\n\n\n<p>3. Zul\u00e4ssigkeit des Zugriffs auf die Analyseberichte<br>3.1 Der Benutzer verpflichtet sich dazu, die ihm \u00fcber das WEBPORTAL \u00fcbermittelten Analyseberichte streng vertraulich zu behandeln.<br>3.2 Der Benutzer darf die Analyseberichte bzw. die daraus gewonnen Erkenntnisse und Informationen nur an solche Personen weitergeben, die von der Einwilligungserkl\u00e4rung und Aufhebung der Verschwiegenheitspflicht durch den Pateinten ausdr\u00fccklich umfasst sind.<br>3.3 Der Benutzer ist verpflichtet, das Ergebnis des Analyseberichtes umgehend an die daf\u00fcr berechtigte Person weiterzugeben.<\/p>\n\n\n\n<p>4. Richtigkeit des Analyseergebnisses<br>4.1 Der Benutzer nimmt zur Kenntnis, dass jede von ARCHIMEDlife durchgef\u00fchrte biochemische und\/ oder genetische Analyse auf dem h\u00f6chsten und aktuellsten wissenschaftlichen und analytischen Standard erfolgt. Dennoch kann nicht ausgeschlossen werden, dass in Einzelf\u00e4llen biochemische oder genetische Tests nicht das richtige Ergebnis anzeigen, wenn beispielsweise die ARCHIMEDlife \u00fcbermittelte Qualit\u00e4t des Materials nicht ausreichend ist oder aus unvorhersehbaren oder unbekannten Gr\u00fcnden fehlschl\u00e4gt, die nicht im Voraus beeinflusst werden kann. In derartigen F\u00e4llen ist ARCHIMEDlife nicht verantwortlich und \/ oder haftbar f\u00fcr das unvollst\u00e4ndige, m\u00f6glicherweise irref\u00fchrende oder sogar falsche Ergebnis der vorgenommenen Analyse, wenn dieser Umstand f\u00fcr ARCHIMEDlife nicht erkennbar war.<br>4.2 Jeder von ARCHIMED verfasste und \u00fcbermittelte Analysebericht gilt nur f\u00fcr die im WEBPORTAL angef\u00fchrte, bestimmte Probe, die unter den angegebenen Testbedingungen und \u2013anforderungen getestet wurde. F\u00fcr die \u00dcbermittlung und Mitteilung des Ergebnisses an den betreffenden Patienten ist ausschlie\u00dflich der Benutzer zust\u00e4ndig \u2013 ARCHIMEDlife haftet in diesem Zusammenhang nicht f\u00fcr Abz\u00fcge, Schlussfolgerungen oder Verallgemeinerungen, die vom Benutzer, dem Partner oder Dritten aus einem Bericht gezogen werden.<br>4.3 Sollte ARCHIMEDlife die urspr\u00fcngliche Analyse bzw.. den Bericht nachpr\u00fcfen m\u00fcssen und dabei weiterf\u00fchrende zus\u00e4tzliche Aufwendungen und Arbeiten erforderlich werden, so ist ARCHIMEDlife berechtigt, diese Mehrkosten zu verrechnen, sofern sich das urspr\u00fcngliche Ergebnis der Analyse best\u00e4tigt.<br>4.4 Die dem Arzt zur Verf\u00fcgung gestellten Berichte k\u00f6nnen von ihm (je nach Umfang der Einwilligungserkl\u00e4rung des Patienten) bzw. dem betreffenden Patienten an den zust\u00e4ndigen Hausarzt oder Dritten \u00fcbermittelt werden, wobei der von ARCHIMEDlife verfasste Analysebericht dabei in seiner Form unver\u00e4ndert bleiben muss. Sollten sich Unklarheiten, Unzul\u00e4nglichkeiten oder anderen m\u00f6gliche M\u00e4ngel in dem Bericht f\u00fcr den verantwortlichen Arzt ergeben, so muss ARCHIMEDlife dar\u00fcber unverz\u00fcglich schriftlich, elektronisch oder telefonisch unter der dem Benutzer bekannt gegebenen Hotline benachrichtigt werden und weitere Erl\u00e4uterungen und eventuelle \u00c4nderungen des Berichtes bzw. eine erneute Analyse verlangen. ARCHIMEDlife wird unverz\u00fcglich eine erneute Untersuchung der Probe vornehmen.<\/p>\n\n\n\n<p>5. WEBPORTAL Support<br>5.1. Technischer Support bei Schwierigkeiten bei der Registrierung im WEBPORTAL bzw. bei der Anmeldung beim Benutzerkonto wird von ARCHIMEDlife per Email bearbeitet unter info@archimedlife.com. Eine Anleitung zur Registrierung und Nutzung des WEBPORTALS findet sich zudem im Einstiegsbereich des WEBPORTALS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ALLGEMEINE GESCH\u00c4FTSBEDINGUNGEN der ARCHIMEDlife GmbHStand: M\u00e4rz 2018 1. Geltungsbereich1.1 Diese Allgemeinen Gesch\u00e4ftsbedingungen gelten f\u00fcr s\u00e4mtliche Vertr\u00e4ge, Angebote, Verk\u00e4ufe, Lieferungen und Dienstleistungen der ARCHIMEDlife GmbH.1.2 Soweit die Parteien einen schriftlichen Vertrag schlie\u00dfen, gehen die Regelungen des Vertrages diesen AGB vor, sofern Widerspr\u00fcche zu den vorliegenden AGBs bestehen. In diesem Fall gelten diese AGB nur f\u00fcr jene<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/www.babyhealthcheck.com\/at\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"ALLGEMEINE GESCH\u00c4FTSBEDINGUNGEN der ARCHIMEDlife GmbHStand: M\u00e4rz 2018 1. Geltungsbereich1.1 Diese Allgemeinen Gesch\u00e4ftsbedingungen gelten f\u00fcr s\u00e4mtliche Vertr\u00e4ge, Angebote, Verk\u00e4ufe, Lieferungen und Dienstleistungen der ARCHIMEDlife GmbH.1.2 Soweit die Parteien einen schriftlichen Vertrag schlie\u00dfen, gehen die Regelungen des Vertrages diesen AGB vor, sofern Widerspr\u00fcche zu den vorliegenden AGBs bestehen. In diesem Fall gelten diese AGB nur f\u00fcr jene","_links":{"self":[{"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/pages\/7342"}],"collection":[{"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/comments?post=7342"}],"version-history":[{"count":3,"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/pages\/7342\/revisions"}],"predecessor-version":[{"id":7461,"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/pages\/7342\/revisions\/7461"}],"wp:attachment":[{"href":"https:\/\/www.babyhealthcheck.com\/at\/wp-json\/wp\/v2\/media?parent=7342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}